{"id":79265,"date":"2016-11-14T10:00:51","date_gmt":"2016-11-14T12:00:51","guid":{"rendered":"https:\/\/www.2beauty.com.br\/blog\/?p=79265"},"modified":"2019-02-15T16:10:02","modified_gmt":"2019-02-15T18:10:02","slug":"boca-colorida-trend-it-up-ultra-matte-lipcream-tons-035-e-090","status":"publish","type":"post","link":"https:\/\/www.2beauty.com.br\/blog\/2016\/11\/boca-colorida-trend-it-up-ultra-matte-lipcream-tons-035-e-090\/","title":{"rendered":"Boca Colorida: Trend It Up Ultra Matte Lipcream (tons #035 e #090)"},"content":{"rendered":"<p style=\"text-align: center\"><strong><a href=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend11.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-79266\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend11.jpg\" alt=\"trend1\" width=\"720\" height=\"470\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend11.jpg 720w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend11-580x378.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend11-620x404.jpg 620w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/strong><\/p>\n<p style=\"text-align: center\"><strong>Trend It Up Ultra Matte Lipcream nos tons #035 e #090<\/strong><\/p>\n<p>Trend It Up \u00e9 uma marca de maquiagem pr\u00f3pria da DM, aquela farm\u00e1cia linda e cheia de produtinhos \u00f3timos que \u00e9 tipo a Panvel germ\u00e2nica :)<\/p>\n<blockquote><p>Sua linha de batons Ultra Matte Lipcream promete a combina\u00e7\u00e3o ideal de cor com acabamento matte e f\u00f3rmula hidratante de longa dura\u00e7\u00e3o.<\/p><\/blockquote>\n<p>Comprei dois tubinhos por apenas \u20ac3,75 euros cada na DM do centro de Bonn.<\/p>\n<p style=\"text-align: center\"><strong><a href=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend21.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-79267\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend21.jpg\" alt=\"trend2\" width=\"720\" height=\"470\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend21.jpg 720w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend21-580x379.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend21-620x405.jpg 620w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/strong><\/p>\n<p style=\"text-align: center\"><strong><a href=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend31.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-79268\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend31.jpg\" alt=\"trend3\" width=\"720\" height=\"470\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend31.jpg 720w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend31-580x378.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend31-620x404.jpg 620w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/strong><\/p>\n<p style=\"text-align: center\"><strong>Amostrinhas<\/strong><\/p>\n<p>#035 \u00e9 um cor de boca rosado mais b\u00e1sico e #090 \u00e9 um vinho bem bonito.<\/p>\n<p>Os batons tem textura mais encorpada e cremosa e um cheirinho gostoso de baunilha.<\/p>\n<blockquote><p>A cor mais clara tem boa cobertura, enquanto a cor mais escura n\u00e3o \u00e9 ruim, mas precisa de duas camadas para ficar realmente homog\u00eanea nos l\u00e1bios.<\/p><\/blockquote>\n<p><strong>INGREDIENTES:<\/strong><br \/>\nDIMETHICONE | ISOSTEARYL ISOSTEARATE | DIMETHICONE CROSSPOLYMER | BIS-DIGLYCERYL POLYACYLADIPATE-2 | DIISOSTEARYL MALATE | KAOLIN | THEOBROMA CACAO SEED BUTTER | SILICA | MALTODEXTRIN | TOCOPHERYL ACETATE | AROMA | TALC | TOCOPHEROL | HELIANTHUS ANNUUS SEED OIL | CI 77742 | CI 75470 | CI 77007 | CI 77891 | CI 77491 | CI 77499 | CI 15850 | CI 77492<\/p>\n<p style=\"text-align: center\"><strong><a href=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend51.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-79270\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend51.jpg\" alt=\"trend5\" width=\"720\" height=\"470\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend51.jpg 720w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend51-580x378.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend51-620x404.jpg 620w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/strong><\/p>\n<p style=\"text-align: center\"><strong>#090<\/strong><\/p>\n<p style=\"text-align: center\"><strong><a href=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-79271\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend6.jpg\" alt=\"trend6\" width=\"720\" height=\"470\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend6.jpg 720w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend6-580x378.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend6-620x404.jpg 620w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/strong><\/p>\n<p style=\"text-align: center\"><strong>#035<\/strong><\/p>\n<p>Os batons s\u00e3o muito confort\u00e1veis e n\u00e3o chegam a secar por completo na boca.<\/p>\n<p>Por conta disso, o acabamento est\u00e1 mais para semi-matte do que para ultra matte e as duas cores acabam transferindo facilmente em copos, guardanapos, etc.<\/p>\n<p>O tom #090 \u00e9 o que d\u00e1 mais trabalho, porque al\u00e9m de transferir, ele pega f\u00e1cil nos dentes.<\/p>\n<blockquote><p>N\u00e3o sei o que houve, mas na primeira hora maquiada com essa cor, toda vez que eu me olhava no espelho, tinha floquinhos de batom nos dentes.<\/p><\/blockquote>\n<p>A\u00ed eu limpava, dava um tempo e&#8230;<\/p>\n<p>Os dentes estavam sujos de novo!<\/p>\n<p style=\"text-align: center\"><strong><a href=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend7.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-79272\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend7.jpg\" alt=\"trend7\" width=\"720\" height=\"470\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend7.jpg 720w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend7-580x378.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend7-620x404.jpg 620w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/strong><\/p>\n<p style=\"text-align: center\"><strong>#090 e #035<\/strong><\/p>\n<p style=\"text-align: center\"><strong><a href=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend41.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-79269\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend41.jpg\" alt=\"trend4\" width=\"720\" height=\"470\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend41.jpg 720w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend41-580x378.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend41-620x404.jpg 620w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/strong><\/p>\n<p style=\"text-align: center\"><strong>Teste do beijinho + close tom #035<\/strong><\/p>\n<p>N\u00e3o passei o tom vinho mais do que duas vezes, porque ele n\u00e3o \u00e9 muito pr\u00e1tico, mas usei e abusei do batom cor de boca enquanto estive em Bonn.<\/p>\n<blockquote><p>N\u00e3o \u00e9 o melhor batom l\u00edquido da vida, mas gostei do tom super fofo e discreto e da f\u00f3rmula com pegada mais hidratante e cremosa, boa pra dia frio e com vento, sabe?<\/p><\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Trend It Up Ultra Matte Lipcream nos tons #035 e #090 Trend It Up \u00e9 uma marca de maquiagem pr\u00f3pria da DM, aquela farm\u00e1cia linda e cheia de produtinhos \u00f3timos que \u00e9 tipo a Panvel germ\u00e2nica :) Sua linha de batons Ultra Matte Lipcream promete a combina\u00e7\u00e3o ideal de cor com acabamento matte e f\u00f3rmula hidratante de longa dura\u00e7\u00e3o. Comprei dois tubinhos por apenas \u20ac3,75 euros cada na DM do centro de Bonn. Amostrinhas #035 \u00e9 um cor de boca rosado mais b\u00e1sico e #090 \u00e9 um vinho bem bonito. Os batons tem textura mais encorpada e cremosa e um cheirinho gostoso de baunilha. A cor mais clara tem boa cobertura, enquanto a cor mais escura n\u00e3o \u00e9 ruim, mas precisa de duas camadas para ficar realmente homog\u00eanea nos l\u00e1bios. INGREDIENTES: DIMETHICONE | ISOSTEARYL ISOSTEARATE | DIMETHICONE CROSSPOLYMER | BIS-DIGLYCERYL POLYACYLADIPATE-2 | DIISOSTEARYL MALATE | KAOLIN | THEOBROMA CACAO SEED BUTTER | SILICA | MALTODEXTRIN | TOCOPHERYL ACETATE | AROMA | TALC | TOCOPHEROL | HELIANTHUS ANNUUS SEED OIL | CI 77742 | CI 75470 | CI 77007 | CI 77891 | CI 77491 | CI 77499 | CI 15850 | CI 77492 #090 #035 Os batons s\u00e3o muito confort\u00e1veis e n\u00e3o chegam a secar por completo na boca. Por conta disso, o acabamento est\u00e1 mais para semi-matte do que para ultra matte e as duas cores acabam transferindo facilmente em copos, guardanapos, etc. O tom #090 \u00e9 o que d\u00e1 mais trabalho, porque al\u00e9m de transferir, ele pega f\u00e1cil nos dentes. N\u00e3o sei o que houve, mas na primeira hora maquiada com essa cor, toda vez que eu me olhava no espelho, tinha floquinhos de batom nos dentes. A\u00ed eu limpava, dava um tempo e&#8230; Os dentes estavam sujos de novo! #090 e #035 Teste do beijinho + close tom #035 N\u00e3o passei o tom vinho mais do que duas vezes, porque ele n\u00e3o \u00e9 muito pr\u00e1tico, mas usei e abusei do batom cor de boca enquanto estive em Bonn. N\u00e3o \u00e9 o melhor batom l\u00edquido da vida, mas gostei do tom super fofo e discreto e da f\u00f3rmula com pegada mais hidratante e cremosa, boa pra dia frio e com vento, sabe?<\/p>\n","protected":false},"author":1,"featured_media":79267,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[84],"tags":[2252,4111,4088,4038],"class_list":["post-79265","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-maquiagem","tag-amostrinhas","tag-batom","tag-maquiagem","tag-trend-it-up"],"uagb_featured_image_src":{"full":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend21.jpg",720,470,false],"thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend21-300x250.jpg",300,250,true],"medium":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend21-580x379.jpg",580,379,true],"medium_large":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend21.jpg",720,470,false],"large":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend21-620x405.jpg",620,405,true],"1536x1536":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend21.jpg",720,470,false],"2048x2048":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend21.jpg",720,470,false],"ashe-slider-grid-thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend21.jpg",720,470,false],"ashe-full-thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend21.jpg",720,470,false],"ashe-grid-thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend21.jpg",500,326,false],"ashe-list-thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend21.jpg",300,196,false],"ashe-single-navigation":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/10\/trend21.jpg",75,49,false]},"uagb_author_info":{"display_name":"Marina Smith","author_link":"https:\/\/www.2beauty.com.br\/blog\/author\/marinasmith\/"},"uagb_comment_info":4,"uagb_excerpt":"Trend It Up Ultra Matte Lipcream nos tons #035 e #090 Trend It Up \u00e9 uma marca de maquiagem pr\u00f3pria da DM, aquela farm\u00e1cia linda e cheia de produtinhos \u00f3timos que \u00e9 tipo a Panvel germ\u00e2nica :) Sua linha de batons Ultra Matte Lipcream promete a combina\u00e7\u00e3o ideal de cor com acabamento matte e f\u00f3rmula&hellip;","acf":[],"_links":{"self":[{"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/posts\/79265","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/comments?post=79265"}],"version-history":[{"count":0,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/posts\/79265\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/media\/79267"}],"wp:attachment":[{"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/media?parent=79265"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/categories?post=79265"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/tags?post=79265"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}