{"id":73743,"date":"2016-05-17T14:39:43","date_gmt":"2016-05-17T16:39:43","guid":{"rendered":"https:\/\/www.2beauty.com.br\/blog\/?p=73743"},"modified":"2019-02-15T16:10:14","modified_gmt":"2019-02-15T18:10:14","slug":"resenha-base-mac-pro-longwear","status":"publish","type":"post","link":"https:\/\/www.2beauty.com.br\/blog\/2016\/05\/resenha-base-mac-pro-longwear\/","title":{"rendered":"Resenha: Base MAC Pro Longwear"},"content":{"rendered":"<p><a href=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac2.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-73746 aligncenter\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac2.jpg\" alt=\"mac2\" width=\"720\" height=\"470\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac2.jpg 720w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac2-580x379.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac2-620x405.jpg 620w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p style=\"text-align: center\"><img decoding=\"async\" style=\"width: 30px;height: 30px\" title=\"Star\" src=\"https:\/\/www.2beauty.com.br\/blog\/images\/star.gif\" alt=\"Star\" width=\"30\" height=\"30\" align=\"top\" border=\"0\" \/><img decoding=\"async\" style=\"width: 30px;height: 30px\" title=\"Star\" src=\"https:\/\/www.2beauty.com.br\/blog\/images\/star.gif\" alt=\"Star\" width=\"30\" height=\"30\" align=\"top\" border=\"0\" \/><img decoding=\"async\" style=\"width: 30px;height: 30px\" title=\"Star\" src=\"https:\/\/www.2beauty.com.br\/blog\/images\/star.gif\" alt=\"Star\" width=\"30\" height=\"30\" align=\"top\" border=\"0\" \/><img decoding=\"async\" style=\"width: 30px;height: 30px\" title=\"Star\" src=\"https:\/\/www.2beauty.com.br\/blog\/images\/star.gif\" alt=\"Star\" width=\"30\" height=\"30\" align=\"top\" border=\"0\" \/><img decoding=\"async\" style=\"width: 30px;height: 30px\" title=\"Star\" src=\"https:\/\/www.2beauty.com.br\/blog\/images\/star2.gif\" alt=\"Star\" width=\"30\" height=\"30\" align=\"top\" border=\"0\" \/><\/p>\n<p style=\"text-align: center\"><strong>Quatro estrelinhas<\/strong><\/p>\n<p>Queria essa base h\u00e1 um temp\u00e3o&#8230;<\/p>\n<p>Desde que testei numa loja AND escutei coment\u00e1rios maravilhosos sobre como ela \u00e9 resistente e se comporta bem em peles oleosas \/ dias mais quentes.<\/p>\n<p>Fora isso, o corretivo dessa linha \u00e9 o meu preferido!<\/p>\n<p>Depois de muito esperar, porque eu tenho umas cinco bases em uso (sem falar nos BB Creams e CC Creams), acabei dizendo dane-se e comprei um frasco.<\/p>\n<p><strong>A descri\u00e7\u00e3o oficial diz o seguinte:<\/strong><\/p>\n<blockquote><p>Base de longa dura\u00e7\u00e3o que confere cobertura por at\u00e9 15 horas em qualquer condi\u00e7\u00e3o ambiental. Sua textura leve e cremosa, suavemente aplicada, cria uma cobertura fina a m\u00e9dia. Controla a oleosidade mantendo a pele fresca, natural e impec\u00e1vel, mesmo em climas quentes e \u00famidos. Confere prote\u00e7\u00e3o solar para o dia-a-dia.<\/p><\/blockquote>\n<p>O meu vidrinho de 30ml <a href=\"https:\/\/www.sephora.com.br\/mac\/maquiagem\/face\/base-pro-longwear-spf-10-foundation-10204?idparceria=29804&amp;utm_source=2beauty&amp;utm_medium=blog&amp;utm_campaign=2beauty\" target=\"_blank\">custou R$146,00 reais no site da Sephora<\/a>.<\/p>\n<p>A base pode ser encontrada <a href=\"https:\/\/www.maccosmetics.com.br\/product\/shaded\/158\/10180\/Products\/Rosto\/Base\/Pro-Longwear-SPF-10-Foundation\/index.tmpl\" target=\"_blank\">nas lojas e no site da MAC pelo mesmo valor<\/a>.<\/p>\n<p style=\"text-align: center\"><strong><a href=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-73747\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac3.jpg\" alt=\"mac3\" width=\"720\" height=\"470\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac3.jpg 720w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac3-580x378.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac3-620x404.jpg 620w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/strong><\/p>\n<p style=\"text-align: center\"><strong> <a href=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-73748\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac4.jpg\" alt=\"mac4\" width=\"720\" height=\"470\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac4.jpg 720w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac4-580x378.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac4-620x404.jpg 620w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/strong><\/p>\n<p style=\"text-align: center\"><strong>Amostrinhas NC40<\/strong><\/p>\n<p>Assim como as outras bases da MAC, a Pro Longwear tem \u00f3tima variedade de tons dos mais claros aos mais escuros.<\/p>\n<p>Normalmente uso NC42, mas optei pela cor NC40, porque a linha Pro Longwear \u00e9 mais escurinha do que as outras.<\/p>\n<p>A textura do produto \u00e9 muito flu\u00edda e a cobertura \u00e9 m\u00e9dia &#8220;potente&#8221;.<\/p>\n<blockquote><p>Logo ao aplicar, a base tem aspecto meio lustroso, mas ela seca depois de uns minutinhos e o acabamento fica matte sem ser pesado.<\/p><\/blockquote>\n<p>Comparada \u00e0 base Studio Fix da mesma marca, por exemplo, a Pro Longwear n\u00e3o cobre tanto, mas tem aspecto mais natural e a sensa\u00e7\u00e3o no rosto tamb\u00e9m \u00e9 mais suave.<\/p>\n<p style=\"text-align: center\"><strong><a href=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac10.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-73754\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac10.jpg\" alt=\"mac10\" width=\"720\" height=\"470\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac10.jpg 720w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac10-580x378.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac10-620x404.jpg 620w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/strong><\/p>\n<p style=\"text-align: center\"><strong><a href=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac9.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-73753\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac9.jpg\" alt=\"mac9\" width=\"720\" height=\"470\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac9.jpg 720w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac9-580x378.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac9-620x404.jpg 620w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/strong><\/p>\n<p style=\"text-align: center\"><strong><a href=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac8.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-73752\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac8.jpg\" alt=\"mac8\" width=\"720\" height=\"470\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac8.jpg 720w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac8-580x378.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac8-620x404.jpg 620w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/strong><\/p>\n<p style=\"text-align: center\"><strong>Pele ao natural e com uma camada de base + close-up + teste de transfer\u00eancia<br \/>\n<\/strong><\/p>\n<p>E voltando \u00e0 aplica\u00e7\u00e3o, vale dizer que \u00e9 bom n\u00e3o se demorar muito ao espalhar o produto, porque depois que seca, n\u00e3o sai do lugar.<\/p>\n<p>Por conta disso, transfere quase nada!<\/p>\n<blockquote><p>Tive que dar um super zoom na foto do teste do lencinho para que o pouco que transferiu ficasse vis\u00edvel na imagem.<\/p><\/blockquote>\n<p>Outra caracter\u00edstica bacana \u00e9 que ela n\u00e3o acumula em linhas nem acentua os poros.<\/p>\n<p>Parece quase pele de verdade, sabe?<\/p>\n<p>Me lembrou um pouco a base HD da Make Up For Ever (<a href=\"https:\/\/www.2beauty.com.br\/blog\/2016\/03\/22\/resenha-make-up-for-ever-ultra-hd-invisible-cover-foundation\/\" target=\"_blank\">resenha aqui<\/a>), s\u00f3 que mais sequinha.<\/p>\n<p style=\"text-align: center\"><a href=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac51.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-76537\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac51.jpg\" alt=\"mac5\" width=\"720\" height=\"470\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac51.jpg 720w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac51-580x378.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac51-620x404.jpg 620w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p style=\"text-align: center\"><strong>Maquiagem pronta \u00e0s 15h com p\u00f3 (Blot Powder) e corretivo (Pro Longwear)<\/strong><\/p>\n<p>E a fixa\u00e7\u00e3o?<\/p>\n<p>A minha pele \u00e9 mista e depois de horas maquiada, o aspecto da base \u00e9 praticamente intacto.<\/p>\n<p>A cobertura se mant\u00e9m e, gra\u00e7as ao combo com o Blot Powder da mesma marca (que \u00e9 amor eterno e verdadeiro), o brilho no meu nariz e testa s\u00e3o m\u00ednimos.<\/p>\n<blockquote><p>Claro que, como eu j\u00e1 falei em outras resenhas de produtos para pele do \u00faltimo m\u00eas, a temperatura em Porto Alegre est\u00e1 colaborando e muito para isso, j\u00e1 que \u00e9 maio e faz frio por aqui.<\/p><\/blockquote>\n<p><strong>Se voc\u00ea tem essa base e mora em lugar mais quente, plis!, comenta se ela segura o tranco e n\u00e3o derrete!<\/strong><\/p>\n<p style=\"text-align: center\"><strong><a href=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac6.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-73750\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac6.jpg\" alt=\"mac6\" width=\"720\" height=\"470\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac6.jpg 720w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac6-580x378.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac6-620x404.jpg 620w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/a><\/strong><\/p>\n<p style=\"text-align: center\"><strong>Maquiagem \u00e0s 23h30min<\/strong><\/p>\n<p><strong>Resumindo:<\/strong><\/p>\n<blockquote><p>Adorei! \u00c9 uma base resistente e de sensa\u00e7\u00e3o leve, acabamento sequinho natural e cobertura m\u00e9dia mais refor\u00e7ada.<\/p>\n<p>Acho que super combina com pele mista ou oleosa, mas falta saber que tal se portar\u00e1 no ver\u00e3o&#8230;<\/p>\n<p>Por enquanto, t\u00f4 achando tudo \u00f3timo (menos o pre\u00e7o).<\/p><\/blockquote>\n<div id=\"resenha\">\n<p><span class=\"titresenha\">Detalhes da nota:<\/span><\/p>\n<div class=\"notas\">Textura\/Aplica\u00e7\u00e3o: 4\/5<br \/>\nCobertura\/Pigmenta\u00e7\u00e3o: 4\/5<br \/>\nFixa\u00e7\u00e3o: 5\/5<br \/>\nPre\u00e7o: 2\/5<br \/>\nApresenta\u00e7\u00e3o: 4\/5<br \/>\nRela\u00e7\u00e3o Realidade x Descri\u00e7\u00e3o Oficial: 5\/5<br \/>\n<span class=\"media\">M\u00e9dia: 4,0<br \/>\n<\/span><\/div>\n<p>Para visualizar a lista completa de crit\u00e9rios e notas, <a href=\"https:\/\/www.2beauty.com.br\/blog\/images\/avaliacao.gif\" target=\"_blank\">clique aqui<\/a>.<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Quatro estrelinhas Queria essa base h\u00e1 um temp\u00e3o&#8230; Desde que testei numa loja AND escutei coment\u00e1rios maravilhosos sobre como ela \u00e9 resistente e se comporta bem em peles oleosas \/ dias mais quentes. Fora isso, o corretivo dessa linha \u00e9 o meu preferido! Depois de muito esperar, porque eu tenho umas cinco bases em uso (sem falar nos BB Creams e CC Creams), acabei dizendo dane-se e comprei um frasco. A descri\u00e7\u00e3o oficial diz o seguinte: Base de longa dura\u00e7\u00e3o que confere cobertura por at\u00e9 15 horas em qualquer condi\u00e7\u00e3o ambiental. Sua textura leve e cremosa, suavemente aplicada, cria uma cobertura fina a m\u00e9dia. Controla a oleosidade mantendo a pele fresca, natural e impec\u00e1vel, mesmo em climas quentes e \u00famidos. Confere prote\u00e7\u00e3o solar para o dia-a-dia. O meu vidrinho de 30ml custou R$146,00 reais no site da Sephora. A base pode ser encontrada nas lojas e no site da MAC pelo mesmo valor. Amostrinhas NC40 Assim como as outras bases da MAC, a Pro Longwear tem \u00f3tima variedade de tons dos mais claros aos mais escuros. Normalmente uso NC42, mas optei pela cor NC40, porque a linha Pro Longwear \u00e9 mais escurinha do que as outras. A textura do produto \u00e9 muito flu\u00edda e a cobertura \u00e9 m\u00e9dia &#8220;potente&#8221;. Logo ao aplicar, a base tem aspecto meio lustroso, mas ela seca depois de uns minutinhos e o acabamento fica matte sem ser pesado. Comparada \u00e0 base Studio Fix da mesma marca, por exemplo, a Pro Longwear n\u00e3o cobre tanto, mas tem aspecto mais natural e a sensa\u00e7\u00e3o no rosto tamb\u00e9m \u00e9 mais suave. Pele ao natural e com uma camada de base + close-up + teste de transfer\u00eancia E voltando \u00e0 aplica\u00e7\u00e3o, vale dizer que \u00e9 bom n\u00e3o se demorar muito ao espalhar o produto, porque depois que seca, n\u00e3o sai do lugar. Por conta disso, transfere quase nada! Tive que dar um super zoom na foto do teste do lencinho para que o pouco que transferiu ficasse vis\u00edvel na imagem. Outra caracter\u00edstica bacana \u00e9 que ela n\u00e3o acumula em linhas nem acentua os poros. Parece quase pele de verdade, sabe? Me lembrou um pouco a base HD da Make Up For Ever (resenha aqui), s\u00f3 que mais sequinha. Maquiagem pronta \u00e0s 15h com p\u00f3 (Blot Powder) e corretivo (Pro Longwear) E a fixa\u00e7\u00e3o? A minha pele \u00e9 mista e depois de horas maquiada, o aspecto da base \u00e9 praticamente intacto. A cobertura se mant\u00e9m e, gra\u00e7as ao combo com o Blot Powder da mesma marca (que \u00e9 amor eterno e verdadeiro), o brilho no meu nariz e testa s\u00e3o m\u00ednimos. Claro que, como eu j\u00e1 falei em outras resenhas de produtos para pele do \u00faltimo m\u00eas, a temperatura em Porto Alegre est\u00e1 colaborando e muito para isso, j\u00e1 que \u00e9 maio e faz frio por aqui. Se voc\u00ea tem essa base e mora em lugar mais quente, plis!, comenta se ela segura o tranco e n\u00e3o derrete! Maquiagem \u00e0s 23h30min Resumindo: Adorei! \u00c9 uma base resistente e de sensa\u00e7\u00e3o leve, acabamento sequinho natural e cobertura m\u00e9dia mais refor\u00e7ada. Acho que super combina com pele mista ou oleosa, mas falta saber que tal se portar\u00e1 no ver\u00e3o&#8230; Por enquanto, t\u00f4 achando tudo \u00f3timo (menos o pre\u00e7o). Detalhes da nota: Textura\/Aplica\u00e7\u00e3o: 4\/5 Cobertura\/Pigmenta\u00e7\u00e3o: 4\/5 Fixa\u00e7\u00e3o: 5\/5 Pre\u00e7o: 2\/5 Apresenta\u00e7\u00e3o: 4\/5 Rela\u00e7\u00e3o Realidade x Descri\u00e7\u00e3o Oficial: 5\/5 M\u00e9dia: 4,0 Para visualizar a lista completa de crit\u00e9rios e notas, clique aqui.<\/p>\n","protected":false},"author":1,"featured_media":73746,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[84],"tags":[4110,221,4088,4128],"class_list":["post-73743","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-maquiagem","tag-base","tag-mac","tag-maquiagem","tag-resenhas"],"uagb_featured_image_src":{"full":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac2.jpg",720,470,false],"thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac2-300x250.jpg",300,250,true],"medium":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac2-580x379.jpg",580,379,true],"medium_large":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac2.jpg",720,470,false],"large":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac2-620x405.jpg",620,405,true],"1536x1536":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac2.jpg",720,470,false],"2048x2048":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac2.jpg",720,470,false],"ashe-slider-grid-thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac2.jpg",720,470,false],"ashe-full-thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac2.jpg",720,470,false],"ashe-grid-thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac2.jpg",500,326,false],"ashe-list-thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac2.jpg",300,196,false],"ashe-single-navigation":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2016\/05\/mac2.jpg",75,49,false]},"uagb_author_info":{"display_name":"Marina Smith","author_link":"https:\/\/www.2beauty.com.br\/blog\/author\/marinasmith\/"},"uagb_comment_info":83,"uagb_excerpt":"Quatro estrelinhas Queria essa base h\u00e1 um temp\u00e3o&#8230; Desde que testei numa loja AND escutei coment\u00e1rios maravilhosos sobre como ela \u00e9 resistente e se comporta bem em peles oleosas \/ dias mais quentes. Fora isso, o corretivo dessa linha \u00e9 o meu preferido! Depois de muito esperar, porque eu tenho umas cinco bases em uso&hellip;","acf":[],"_links":{"self":[{"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/posts\/73743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/comments?post=73743"}],"version-history":[{"count":0,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/posts\/73743\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/media\/73746"}],"wp:attachment":[{"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/media?parent=73743"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/categories?post=73743"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/tags?post=73743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}