{"id":54438,"date":"2014-04-16T16:00:42","date_gmt":"2014-04-16T18:00:42","guid":{"rendered":"https:\/\/www.2beauty.com.br\/blog\/?p=54438"},"modified":"2019-02-15T16:11:06","modified_gmt":"2019-02-15T18:11:06","slug":"boca-colorida-batom-superstay-14hr-lipstick-maybelline-cor-please-stay-plum","status":"publish","type":"post","link":"https:\/\/www.2beauty.com.br\/blog\/2014\/04\/boca-colorida-batom-superstay-14hr-lipstick-maybelline-cor-please-stay-plum\/","title":{"rendered":"Boca Colorida: Batom SuperStay 14hr Lipstick Maybelline cor Please Stay Plum"},"content":{"rendered":"<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum1.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone size-full wp-image-54439\" alt=\"pleasestayplum1\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum1.jpg\" width=\"620\" height=\"932\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum1.jpg 620w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum1-580x872.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum1-289x435.jpg 289w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/a><\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Batom SuperStay 14hr Lipstick Maybelline cor Please Stay Plum<\/strong><\/p>\n<p>Eu tenho um batom vinho dessa linha 14 horas da Maybelline que gosto muito (<a href=\"https:\/\/www.2beauty.com.br\/blog\/2013\/04\/17\/resenha-batom-superstay-14hr-lipstick-maybelline-cor-wine-forever\/\" target=\"_blank\">resenha aqui<\/a>) e quando encontrei mais algumas cores na Farmacity, n\u00e3o tive d\u00favidas!<\/p>\n<p>Escolhi a mais bonita das que estavam dispon\u00edveis e levei pro caixa.<\/p>\n<blockquote><p>A f\u00f3rmula dos batons SuperStay 14hr foi feita para dar boa cobertura e alta fixa\u00e7\u00e3o sem ressecar os l\u00e1bios (j\u00e1 que o ressecamento \u00e9 comum em alguns batons de longa dura\u00e7\u00e3o).<\/p><\/blockquote>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum2.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-54440\" alt=\"pleasestayplum2\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum2.jpg\" width=\"620\" height=\"412\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum2.jpg 620w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum2-580x385.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum2-250x166.jpg 250w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/a><\/strong><\/p>\n<p style=\"text-align: center;\"><strong> <a href=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum3.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-54441\" alt=\"pleasestayplum3\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum3.jpg\" width=\"620\" height=\"412\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum3.jpg 620w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum3-580x385.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum3-250x166.jpg 250w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/a><\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Amostrinha Please Stay Plum<\/strong><\/p>\n<p>Pela minha experi\u00eancia, as cores n\u00e3o s\u00e3o capazes de durar as tais 14 horas, mas a fixa\u00e7\u00e3o \u00e9 melhor que a de batons comuns.<\/p>\n<p>Infelizmente, essa linha ainda n\u00e3o chegou ao Brasil.<\/p>\n<p><strong>Na Argentina, voc\u00ea encontra por $96 pesos. Nos EUA, por apenas $8 d\u00f3lares.<\/strong><\/p>\n<p style=\"text-align: center;\"><strong><a href=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-54442\" alt=\"pleasestayplum4\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum4.jpg\" width=\"620\" height=\"412\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum4.jpg 620w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum4-580x385.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum4-250x166.jpg 250w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/a><\/strong><\/p>\n<p style=\"text-align: center;\"><strong> <a href=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-54443\" alt=\"pleasestayplum5\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum5.jpg\" width=\"620\" height=\"932\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum5.jpg 620w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum5-289x435.jpg 289w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum5-250x375.jpg 250w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/a><\/strong><\/p>\n<p style=\"text-align: center;\"><strong>Please Stay Plum em close e no car\u00e3o<\/strong><\/p>\n<p>Please Stay Plum \u00e9 um ameixa rosado com acabamento levemente cintilante.<\/p>\n<p>A textura \u00e9 boa e o batom desliza com facilidade sobre a boca.<\/p>\n<p>Logo que voc\u00ea aplica, o aspecto \u00e9 mais cremoso. Com o passar do tempo, ele vai secando, mas n\u00e3o incomoda os l\u00e1bios.<\/p>\n<p><strong>A pigmenta\u00e7\u00e3o \u00e9 bacana e mesmo ele n\u00e3o durando um dia inteiro (n\u00e3o resiste \u00e0s refei\u00e7\u00f5es), gosto muito.<\/strong><\/p>\n<p>Da pr\u00f3xima vez que viajar, vou procurar os vermelhos dessa linha :)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Batom SuperStay 14hr Lipstick Maybelline cor Please Stay Plum Eu tenho um batom vinho dessa linha 14 horas da Maybelline que gosto muito (resenha aqui) e quando encontrei mais algumas cores na Farmacity, n\u00e3o tive d\u00favidas! Escolhi a mais bonita das que estavam dispon\u00edveis e levei pro caixa. A f\u00f3rmula dos batons SuperStay 14hr foi feita para dar boa cobertura e alta fixa\u00e7\u00e3o sem ressecar os l\u00e1bios (j\u00e1 que o ressecamento \u00e9 comum em alguns batons de longa dura\u00e7\u00e3o). Amostrinha Please Stay Plum Pela minha experi\u00eancia, as cores n\u00e3o s\u00e3o capazes de durar as tais 14 horas, mas a fixa\u00e7\u00e3o \u00e9 melhor que a de batons comuns. Infelizmente, essa linha ainda n\u00e3o chegou ao Brasil. Na Argentina, voc\u00ea encontra por $96 pesos. Nos EUA, por apenas $8 d\u00f3lares. Please Stay Plum em close e no car\u00e3o Please Stay Plum \u00e9 um ameixa rosado com acabamento levemente cintilante. A textura \u00e9 boa e o batom desliza com facilidade sobre a boca. Logo que voc\u00ea aplica, o aspecto \u00e9 mais cremoso. Com o passar do tempo, ele vai secando, mas n\u00e3o incomoda os l\u00e1bios. A pigmenta\u00e7\u00e3o \u00e9 bacana e mesmo ele n\u00e3o durando um dia inteiro (n\u00e3o resiste \u00e0s refei\u00e7\u00f5es), gosto muito. Da pr\u00f3xima vez que viajar, vou procurar os vermelhos dessa linha :)<\/p>\n","protected":false},"author":1,"featured_media":54439,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[84],"tags":[2252,4111,4088,300,3689,3690],"class_list":["post-54438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-maquiagem","tag-amostrinhas","tag-batom","tag-maquiagem","tag-maybelline","tag-please-stay-plum","tag-superstay-14hr-lipstick"],"uagb_featured_image_src":{"full":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum1.jpg",620,932,false],"thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum1-300x250.jpg",300,250,true],"medium":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum1-289x435.jpg",289,435,true],"medium_large":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum1.jpg",620,932,false],"large":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum1-620x932.jpg",620,932,true],"1536x1536":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum1.jpg",620,932,false],"2048x2048":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum1.jpg",620,932,false],"ashe-slider-grid-thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum1.jpg",359,540,false],"ashe-full-thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum1.jpg",620,932,false],"ashe-grid-thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum1.jpg",220,330,false],"ashe-list-thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum1.jpg",200,300,false],"ashe-single-navigation":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2014\/04\/pleasestayplum1.jpg",50,75,false]},"uagb_author_info":{"display_name":"Marina Smith","author_link":"https:\/\/www.2beauty.com.br\/blog\/author\/marinasmith\/"},"uagb_comment_info":9,"uagb_excerpt":"Batom SuperStay 14hr Lipstick Maybelline cor Please Stay Plum Eu tenho um batom vinho dessa linha 14 horas da Maybelline que gosto muito (resenha aqui) e quando encontrei mais algumas cores na Farmacity, n\u00e3o tive d\u00favidas! Escolhi a mais bonita das que estavam dispon\u00edveis e levei pro caixa. A f\u00f3rmula dos batons SuperStay 14hr foi&hellip;","acf":[],"_links":{"self":[{"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/posts\/54438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/comments?post=54438"}],"version-history":[{"count":0,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/posts\/54438\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/media\/54439"}],"wp:attachment":[{"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/media?parent=54438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/categories?post=54438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/tags?post=54438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}