{"id":41613,"date":"2013-02-25T14:00:04","date_gmt":"2013-02-25T16:00:04","guid":{"rendered":"https:\/\/www.2beauty.com.br\/blog\/?p=41613"},"modified":"2019-02-15T16:11:38","modified_gmt":"2019-02-15T18:11:38","slug":"dica-da-leitora-mac-em-rivera","status":"publish","type":"post","link":"https:\/\/www.2beauty.com.br\/blog\/2013\/02\/dica-da-leitora-mac-em-rivera\/","title":{"rendered":"Dica da Leitora: MAC em Rivera"},"content":{"rendered":"<p><a href=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2013\/02\/MAC-Black-Free-Shop-Legendas.jpg\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-41614 aligncenter\" alt=\"MAC-Black-Free-Shop-Legendas\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2013\/02\/MAC-Black-Free-Shop-Legendas.jpg\" width=\"620\" height=\"465\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2013\/02\/MAC-Black-Free-Shop-Legendas.jpg 620w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2013\/02\/MAC-Black-Free-Shop-Legendas-580x435.jpg 580w\" sizes=\"(max-width: 620px) 100vw, 620px\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><strong>Sim, tem MAC em Rivera :)<\/strong><\/p>\n<p>Muito obrigada \u00e0 leitora Elaine pela dica MARAVIS e pelo super texto com todos os detalhes dos produtos da MAC encontrados em Rivera (pre\u00e7os, variedade de cores, etc.).<\/p>\n<p><strong>Aqui vai:<\/strong><\/p>\n<p>Rivera, janeiro de 2013. Estamos em um dos free shops mais conhecidos, quase indo embora, quando uma vendedora sussura baixinho, em tom conspirat\u00f3rio: \u2014\u00a1Ah\u00ed en frente hay MAC! Custei a entender: \u2014\u00a1\u00bfQu\u00e9?! \u2014\u00a1MAC! \u2014\u00bfC\u00f3mo se llama el free shop? \u2014\u00a1Black! \u2014\u00bfMAC? \u2014\u00a1Black!<\/p>\n<p>J\u00e1 tinha escutado algum rumor de que haveria MAC em Rivera. Como n\u00e3o achei nada na internet e nenhuma conhecida sabia de alguma coisa, esqueci do assunto. Sequer me passou pela cabe\u00e7a tirar essa hist\u00f3ria a limpo, quando cheguei l\u00e1.<\/p>\n<blockquote><p>Bom, o caso \u00e9 que, gra\u00e7as \u00e0 vendedora da loja concorrente, fiquei sabendo que tem MAC em Rivera, no Black Free Shop, na matriz \u00e0 rua Paysand\u00fa, 1140 (entre Sarand\u00ed e Ituzaing\u00f3) e na filialzinha da Sarand\u00ed, entre as ruas Figueroa e Faustino Carambula.<\/p><\/blockquote>\n<p>Na Paysand\u00fa deve ter a\u00ed uma d\u00fazia de itens, entre eles: base em p\u00f3 Studio Fix, base l\u00edquida Studio Fix Fluid, corretivo Studio Finish, corretivo Pro Longwear, batons, sombras compactas em uma razo\u00e1vel gama de cores, r\u00edmel e c\u00edlios posti\u00e7os. Nada de pinc\u00e9is, sombras em refil, MSF, Paint Pots ou outras bases.<\/p>\n<blockquote><p>O free shop resume-se a duas salas. Em uma tem games e notebooks, na outra, Victoria Secret\u2019s e MAC, tudo atr\u00e1s de balc\u00f5es.<\/p><\/blockquote>\n<p>Os pre\u00e7os, se comparados com os dos Estados Unidos, est\u00e3o bem salgados, em m\u00e9dia 77% mais caros, o que destoa do pre\u00e7o geral dos cosm\u00e9ticos no resto das lojas de Rivera. \u00c9 poss\u00edvel que a concorr\u00eancia incorpore MAC ao estoque num futuro pr\u00f3ximo, fazendo com que os pre\u00e7os baixem. A DFA, por exemplo est\u00e1 planejando uma reformula\u00e7\u00e3o grande para este ano, a Neutral, um novo x\u00f3pim. \u00a1Y ya veremos!<\/p>\n<p><strong>Vamos aos pre\u00e7os:<\/strong><\/p>\n<ul>\n<li>Batons \u2013 US $ 26<\/li>\n<li>Base em p\u00f3 Studio Fix Powder \u2013 US $ 47<\/li>\n<li>Base l\u00edquida Studio Fix Fluid 30ml \u2013 US $ 47 (podia experimentar os tons)<\/li>\n<li>Corretivo Pro Longwear 9ml \u2013 US $ 32 (podia experimentar)<\/li>\n<li>Corretivo Studio Finish 7g \u2013 US $ 32 (podia experimentar). Em mim, o danado \u201ccrisou\u201d no mesmo instante! Mas nem liguem, claro que apliquei mal e parcamente.<\/li>\n<li>Sombras \u2013 US $ 28. S\u00f3 no potinho preto. Cores: Satin Taupe, Rice Paper, Nylon, Espresso e v\u00e1rias outras.<\/li>\n<\/ul>\n<blockquote><p>Site: <a href=\"https:\/\/www.blackfreeshop.com\/\" target=\"_blank\">https:\/\/www.blackfreeshop.com\/<\/a><\/p><\/blockquote>\n<p>Recomendo uma paradinha no Caf\u00e9 La Familia, do outro lado da rua, para provar uma aut\u00eantica tarta pascualina uruguaia.<\/p>\n<p>Pra quem ainda n\u00e3o sabe, Rivera \u00e9 uma cidade uruguaia na fronteira com o Brasil, cheia de free shops. Atravessando uma simples avenida se est\u00e1 em Santana do Livramento, no Rio Grande do Sul. Porto Alegre fica a 480 km de dist\u00e2ncia. Como em todos os outros free shops oficializados da fronteira Uruguai-Brasil, a mercadoria \u00e9 garantida e o risco de comprar falsifica\u00e7\u00f5es \u00e9 muito baixo.<\/p>\n<p>Bj, Elaine<\/p>\n<p style=\"text-align: center;\">. . . . . . . . . .<\/p>\n<p style=\"text-align: center;\"><strong>Muuuuuuito obrigada pela dica, Elaine! :)<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sim, tem MAC em Rivera :) Muito obrigada \u00e0 leitora Elaine pela dica MARAVIS e pelo super texto com todos os detalhes dos produtos da MAC encontrados em Rivera (pre\u00e7os, variedade de cores, etc.). Aqui vai: Rivera, janeiro de 2013. Estamos em um dos free shops mais conhecidos, quase indo embora, quando uma vendedora sussura baixinho, em tom conspirat\u00f3rio: \u2014\u00a1Ah\u00ed en frente hay MAC! Custei a entender: \u2014\u00a1\u00bfQu\u00e9?! \u2014\u00a1MAC! \u2014\u00bfC\u00f3mo se llama el free shop? \u2014\u00a1Black! \u2014\u00bfMAC? \u2014\u00a1Black! J\u00e1 tinha escutado algum rumor de que haveria MAC em Rivera. Como n\u00e3o achei nada na internet e nenhuma conhecida sabia de alguma coisa, esqueci do assunto. Sequer me passou pela cabe\u00e7a tirar essa hist\u00f3ria a limpo, quando cheguei l\u00e1. Bom, o caso \u00e9 que, gra\u00e7as \u00e0 vendedora da loja concorrente, fiquei sabendo que tem MAC em Rivera, no Black Free Shop, na matriz \u00e0 rua Paysand\u00fa, 1140 (entre Sarand\u00ed e Ituzaing\u00f3) e na filialzinha da Sarand\u00ed, entre as ruas Figueroa e Faustino Carambula. Na Paysand\u00fa deve ter a\u00ed uma d\u00fazia de itens, entre eles: base em p\u00f3 Studio Fix, base l\u00edquida Studio Fix Fluid, corretivo Studio Finish, corretivo Pro Longwear, batons, sombras compactas em uma razo\u00e1vel gama de cores, r\u00edmel e c\u00edlios posti\u00e7os. Nada de pinc\u00e9is, sombras em refil, MSF, Paint Pots ou outras bases. O free shop resume-se a duas salas. Em uma tem games e notebooks, na outra, Victoria Secret\u2019s e MAC, tudo atr\u00e1s de balc\u00f5es. Os pre\u00e7os, se comparados com os dos Estados Unidos, est\u00e3o bem salgados, em m\u00e9dia 77% mais caros, o que destoa do pre\u00e7o geral dos cosm\u00e9ticos no resto das lojas de Rivera. \u00c9 poss\u00edvel que a concorr\u00eancia incorpore MAC ao estoque num futuro pr\u00f3ximo, fazendo com que os pre\u00e7os baixem. A DFA, por exemplo est\u00e1 planejando uma reformula\u00e7\u00e3o grande para este ano, a Neutral, um novo x\u00f3pim. \u00a1Y ya veremos! Vamos aos pre\u00e7os: Batons \u2013 US $ 26 Base em p\u00f3 Studio Fix Powder \u2013 US $ 47 Base l\u00edquida Studio Fix Fluid 30ml \u2013 US $ 47 (podia experimentar os tons) Corretivo Pro Longwear 9ml \u2013 US $ 32 (podia experimentar) Corretivo Studio Finish 7g \u2013 US $ 32 (podia experimentar). Em mim, o danado \u201ccrisou\u201d no mesmo instante! Mas nem liguem, claro que apliquei mal e parcamente. Sombras \u2013 US $ 28. S\u00f3 no potinho preto. Cores: Satin Taupe, Rice Paper, Nylon, Espresso e v\u00e1rias outras. Site: https:\/\/www.blackfreeshop.com\/ Recomendo uma paradinha no Caf\u00e9 La Familia, do outro lado da rua, para provar uma aut\u00eantica tarta pascualina uruguaia. Pra quem ainda n\u00e3o sabe, Rivera \u00e9 uma cidade uruguaia na fronteira com o Brasil, cheia de free shops. Atravessando uma simples avenida se est\u00e1 em Santana do Livramento, no Rio Grande do Sul. Porto Alegre fica a 480 km de dist\u00e2ncia. Como em todos os outros free shops oficializados da fronteira Uruguai-Brasil, a mercadoria \u00e9 garantida e o risco de comprar falsifica\u00e7\u00f5es \u00e9 muito baixo. Bj, Elaine . . . . . . . . . . Muuuuuuito obrigada pela dica, Elaine! :)<\/p>\n","protected":false},"author":1,"featured_media":41614,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[1],"tags":[2673,221,4127,651],"class_list":["post-41613","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","tag-compras-na-fronteira","tag-mac","tag-onde-comprar","tag-rivera"],"uagb_featured_image_src":{"full":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2013\/02\/MAC-Black-Free-Shop-Legendas.jpg",620,465,false],"thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2013\/02\/MAC-Black-Free-Shop-Legendas-300x250.jpg",300,250,true],"medium":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2013\/02\/MAC-Black-Free-Shop-Legendas-580x435.jpg",580,435,true],"medium_large":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2013\/02\/MAC-Black-Free-Shop-Legendas.jpg",620,465,false],"large":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2013\/02\/MAC-Black-Free-Shop-Legendas-620x465.jpg",620,465,true],"1536x1536":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2013\/02\/MAC-Black-Free-Shop-Legendas.jpg",620,465,false],"2048x2048":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2013\/02\/MAC-Black-Free-Shop-Legendas.jpg",620,465,false],"ashe-slider-grid-thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2013\/02\/MAC-Black-Free-Shop-Legendas.jpg",620,465,false],"ashe-full-thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2013\/02\/MAC-Black-Free-Shop-Legendas.jpg",620,465,false],"ashe-grid-thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2013\/02\/MAC-Black-Free-Shop-Legendas.jpg",440,330,false],"ashe-list-thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2013\/02\/MAC-Black-Free-Shop-Legendas.jpg",300,225,false],"ashe-single-navigation":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2013\/02\/MAC-Black-Free-Shop-Legendas.jpg",75,56,false]},"uagb_author_info":{"display_name":"Marina Smith","author_link":"https:\/\/www.2beauty.com.br\/blog\/author\/marinasmith\/"},"uagb_comment_info":47,"uagb_excerpt":"Sim, tem MAC em Rivera :) Muito obrigada \u00e0 leitora Elaine pela dica MARAVIS e pelo super texto com todos os detalhes dos produtos da MAC encontrados em Rivera (pre\u00e7os, variedade de cores, etc.). Aqui vai: Rivera, janeiro de 2013. Estamos em um dos free shops mais conhecidos, quase indo embora, quando uma vendedora sussura&hellip;","acf":[],"_links":{"self":[{"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/posts\/41613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/comments?post=41613"}],"version-history":[{"count":0,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/posts\/41613\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/media\/41614"}],"wp:attachment":[{"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/media?parent=41613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/categories?post=41613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/tags?post=41613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}