{"id":115684,"date":"2020-05-18T17:37:45","date_gmt":"2020-05-18T19:37:45","guid":{"rendered":"https:\/\/www.2beauty.com.br\/blog\/?p=115684"},"modified":"2020-05-20T20:15:30","modified_gmt":"2020-05-20T22:15:30","slug":"coronaflix-10-documentarios-da-hbo-sobre-crime-real","status":"publish","type":"post","link":"https:\/\/www.2beauty.com.br\/blog\/2020\/05\/coronaflix-10-documentarios-da-hbo-sobre-crime-real\/","title":{"rendered":"#CoronaFlix: 10 document\u00e1rios da HBO sobre crime real"},"content":{"rendered":"\n<script async=\"\" src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<!-- Responsivo www.2beauty.com.br -->\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-client=\"ca-pub-5401592170963248\" data-ad-slot=\"6719035301\" data-ad-format=\"auto\" data-full-width-responsive=\"true\"><\/ins>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<figure class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/0.jpg\" alt=\"#CoronaFlix: 10 document\u00e1rios da HBO sobre crime real\" class=\"wp-image-115688\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/0.jpg 900w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/0-580x387.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/0-768x512.jpg 768w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/0-620x413.jpg 620w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/0-860x573.jpg 860w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p>Voc\u00eas j\u00e1 est\u00e3o carecas de saber que me interesso muito por <strong>document\u00e1rios e hist\u00f3rias de crime real.<\/strong><\/p>\n\n\n\n<p>Sou assinante HBO Go e apesar de achar o app uma droga, devo admitir que o servi\u00e7o tem um cat\u00e1logo com t\u00edtulos muito impactantes tanto sobre casos mais famosos quanto crimes menos conhecidos.<\/p>\n\n\n\n<p>Aqui est\u00e1 uma listinha com 10 docs e miniss\u00e9ries que assisti e recomendo.<\/p>\n\n\n\n<p><strong>Vamos l\u00e1:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/1-1.jpg\" alt=\"#CoronaFlix: 10 document\u00e1rios da HBO sobre crime real\" class=\"wp-image-115689\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/1-1.jpg 900w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/1-1-580x387.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/1-1-768x512.jpg 768w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/1-1-620x413.jpg 620w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/1-1-860x573.jpg 860w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Os Assassinatos de Cheshire<\/h3>\n\n\n\n<p>Este document\u00e1rio analisa a pena de morte a partir dos assassinatos ocorridos em Cheshire, em 2007, quando dois ex-presidi\u00e1rios mataram brutalmente uma fam\u00edlia.<\/p>\n\n\n\n<p>A investiga\u00e7\u00e3o revela como o sistema de justi\u00e7a do estado acaba tomando a pol\u00eamica decis\u00e3o de, em fun\u00e7\u00e3o do custo de um processo de pena de morte, condenar os assassinos \u00e0 pris\u00e3o perp\u00e9tua. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">O Caso do Policial Canibal<\/h3>\n\n\n\n<p>Apelidado de &#8220;o policial canibal&#8221;, Gilberto Valle foi  condenado em mar\u00e7o de 2013, acusado de planejar o sequestro de mulheres  para assassin\u00e1-las e com\u00ea-las.<\/p>\n\n\n\n<p>Depois de 22 meses atr\u00e1s das grades, sua pena foi revogada em meio a uma grande pol\u00eamica sobre a diferen\u00e7a entre pensamentos compartilhados na internet e crimes realmente executados. <\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/2-1.jpg\" alt=\"#CoronaFlix: 10 document\u00e1rios da HBO sobre crime real\" class=\"wp-image-115690\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/2-1.jpg 900w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/2-1-580x387.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/2-1-768x512.jpg 768w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/2-1-620x413.jpg 620w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/2-1-860x573.jpg 860w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">The Jinx: The Life And Deaths Of Robert Durst<\/h3>\n\n\n\n<p>O diretor Andrew Jarecki dirigiu o filme <em>Entre Segredos e Mentiras<\/em> (All Good Things, 2010), inspirado na biografia de Robert Durst, herdeiro do setor imobili\u00e1rio de Nova York. <\/p>\n\n\n\n<p>O longa valeu a Jarecki a admira\u00e7\u00e3o de Durst, que topou ser entrevistado para o document\u00e1rio.<\/p>\n\n\n\n<p>Por meio de mais de 20 horas de entrevistas ao longo de v\u00e1rios anos, Jarecki mostra a complexa vida do milion\u00e1rio ap\u00f3s ter sido acusado de tr\u00eas assassinatos em quatro d\u00e9cadas. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Cuidado Com o Slenderman<\/h3>\n\n\n\n<p>Anissa Weier e Morgan Geyser, duas garotas de 12 anos, apunhalaram sua colega de escola Payton Leutner, porque queriam  demonstrar sua lealdade ao Slenderman, um personagem fict\u00edcio que surgiu na internet, e assim evitar que ele matasse suas fam\u00edlias.<\/p>\n\n\n\n<p>O document\u00e1rio examina como o isolamento adolescente e a natureza conflituosa da internet geraram uma trag\u00e9dia para todos os envolvidos.&nbsp; <\/p>\n\n\n\n<script async=\"\" src=\"\/\/pagead2.googlesyndication.com\/pagead\/js\/adsbygoogle.js\"><\/script>\n<!-- Responsivo www.2beauty.com.br -->\n<ins class=\"adsbygoogle\" style=\"display:block\" data-ad-client=\"ca-pub-5401592170963248\" data-ad-slot=\"6719035301\" data-ad-format=\"auto\" data-full-width-responsive=\"true\"><\/ins>\n<script>\n(adsbygoogle = window.adsbygoogle || []).push({});\n<\/script>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/3-1.jpg\" alt=\"#CoronaFlix: 10 document\u00e1rios da HBO sobre crime real\" class=\"wp-image-115691\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/3-1.jpg 900w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/3-1-580x387.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/3-1-768x512.jpg 768w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/3-1-620x413.jpg 620w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/3-1-860x573.jpg 860w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Mam\u00e3e Morta e Querida<\/h3>\n\n\n\n<p>O document\u00e1rio relata a hist\u00f3ria do assassinato de  Dee Dee Blanchard, cometido por sua filha Gypsy Rose Blanchard e o  namorado Nicholas Godejohn.<\/p>\n\n\n\n<p>Durante anos Dee Dee, que sofria de uma doen\u00e7a mental chamada s\u00edndrome de M\u00fcnchhausen, abusou psicologicamente de sua filha, convencendo-a de que sofria uma s\u00e9rie de doen\u00e7as como leucemia, asma, distrofia muscular, e que tinha a capacidade mental de uma menina de 7 anos por causa de um dano cerebral. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">The Case Against Adnan Syed<\/h3>\n\n\n\n<p>Esta s\u00e9rie documental reexamina o desaparecimento e assassinato da estudante Hae Min Lee em 1999, e a subsequente condena\u00e7\u00e3o de seu ex-namorado Adnan Syed, um caso tornado famoso pelo popular podcast &#8220;Serial&#8221;.<\/p>\n\n\n\n<p>Hoje ele cumpre pris\u00e3o perp\u00e9tua apesar de ter tentado, v\u00e1rias vezes, ser submetido a um novo julgamento para provar sua inoc\u00eancia.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/4-1.jpg\" alt=\"#CoronaFlix: 10 document\u00e1rios da HBO sobre crime real\" class=\"wp-image-115692\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/4-1.jpg 900w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/4-1-580x387.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/4-1-768x512.jpg 768w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/4-1-620x413.jpg 620w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/4-1-860x573.jpg 860w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Eu Te Amo, Agora Morra<\/h3>\n\n\n\n<p>A rela\u00e7\u00e3o que Michelle Carter e Conrad Roy estabeleceram por meio de mensagens e liga\u00e7\u00f5es durante dois anos terminou quando Conrad Roy cometeu suic\u00eddio por intoxica\u00e7\u00e3o com mon\u00f3xido de carbono.<\/p>\n\n\n\n<p>Os investigadores encontraram provas de que Carter supostamente o teria encorajado a se suicidar.<\/p>\n\n\n\n<p>O document\u00e1rio analisa o julgamento de Michelle Carter que foi presa por homic\u00eddio involunt\u00e1rio.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Quem Matou Garrett Phillips<\/h3>\n\n\n\n<p>O document\u00e1rio examina os acontecimentos ap\u00f3s o assassinato de Garrett Phillips, de 12 anos, desde a investiga\u00e7\u00e3o inicial at\u00e9 a pris\u00e3o e julgamento de Oral \u201cNick\u201d Hillary, um t\u00e9cnico de futebol negro que vive em uma comunidade predominantemente branca.<\/p>\n\n\n\n<p>Al\u00e9m de abordar as enigm\u00e1ticas circunst\u00e2ncias do caso, o document\u00e1rio levanta quest\u00f5es sociais mais amplas, como o racismo dentro sistema de justi\u00e7a penal.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"600\" src=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/5-1.jpg\" alt=\"#CoronaFlix: 10 document\u00e1rios da HBO sobre crime real\" class=\"wp-image-115693\" srcset=\"https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/5-1.jpg 900w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/5-1-580x387.jpg 580w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/5-1-768x512.jpg 768w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/5-1-620x413.jpg 620w, https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/5-1-860x573.jpg 860w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">McMillion$<\/h3>\n\n\n\n<p>S\u00e9rie documental de seis epis\u00f3dios que explora o impressionante caso da mente criminosa conhecida como \u201dUncle Jerry\u201d, que  entre 1989 e 2001 deu golpes envolvendo uma a\u00e7\u00e3o promocional do McDonald\u2019s.<\/p>\n\n\n\n<p>Ao roubar cartelas valiosas do jogo, Jerry conseguiu selecionar os ganhadores manualmente, enganar as autoridades e  compartilhar os pr\u00eamios de forma il\u00edcita.<\/p>\n\n\n\n<p>A fraude, que come\u00e7ou com a fam\u00edlia e os amigos de Jerry, rapidamente se expandiu e chegou a envolver ex-presidi\u00e1rios ligados \u00e0 m\u00e1fia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Atlanta&#8217;s Missing And Murdered: The Lost Children <\/h3>\n\n\n\n<p>Conhecida como &#8220;a cidade muito ocupada para odiar&#8221; (<em>the city too busy to hate<\/em>), Atlanta prosperou com a elei\u00e7\u00e3o do primeiro prefeito negro na d\u00e9cada de 70.<\/p>\n\n\n\n<p>Entretanto, abaixo da superf\u00edcie, divis\u00f5es raciais e econ\u00f4micas de longa data continuam existindo. <\/p>\n\n\n\n<p>A miniss\u00e9rie em cinco partes analisa evid\u00eancias envolvendo os assassinatos de pelo menos 30 crian\u00e7as e jovens negros que ocorreram durante um per\u00edodo de dois anos na capital da Ge\u00f3rgia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sou assinante HBO Go e apesar de achar o app uma droga, devo admitir que o servi\u00e7o tem um cat\u00e1logo com t\u00edtulos muito impactantes.<\/p>\n","protected":false},"author":1,"featured_media":115688,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","footnotes":""},"categories":[1],"tags":[4543,4547,4391,4442],"class_list":["post-115684","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","tag-coronaflix","tag-crime-real","tag-documentarios","tag-hbo-go"],"uagb_featured_image_src":{"full":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/0.jpg",900,600,false],"thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/0-300x250.jpg",300,250,true],"medium":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/0-580x387.jpg",580,387,true],"medium_large":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/0-768x512.jpg",768,512,true],"large":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/0-620x413.jpg",620,413,true],"1536x1536":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/0.jpg",900,600,false],"2048x2048":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/0.jpg",900,600,false],"ashe-slider-grid-thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/0.jpg",810,540,false],"ashe-full-thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/0.jpg",900,600,false],"ashe-grid-thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/0.jpg",495,330,false],"ashe-list-thumbnail":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/0.jpg",300,200,false],"ashe-single-navigation":["https:\/\/www.2beauty.com.br\/blog\/wp-content\/uploads\/2020\/05\/0.jpg",75,50,false]},"uagb_author_info":{"display_name":"Marina Smith","author_link":"https:\/\/www.2beauty.com.br\/blog\/author\/marinasmith\/"},"uagb_comment_info":2,"uagb_excerpt":"Sou assinante HBO Go e apesar de achar o app uma droga, devo admitir que o servi\u00e7o tem um cat\u00e1logo com t\u00edtulos muito impactantes.","acf":[],"_links":{"self":[{"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/posts\/115684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/comments?post=115684"}],"version-history":[{"count":3,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/posts\/115684\/revisions"}],"predecessor-version":[{"id":115716,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/posts\/115684\/revisions\/115716"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/media\/115688"}],"wp:attachment":[{"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/media?parent=115684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/categories?post=115684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.2beauty.com.br\/blog\/wp-json\/wp\/v2\/tags?post=115684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}